{"id":690,"date":"2016-06-06T12:45:30","date_gmt":"2016-06-06T11:45:30","guid":{"rendered":"http:\/\/arxiversvalencians.org\/wordpress\/es\/quan-luciana-duranti-baixa-del-nuvol\/"},"modified":"2016-06-06T12:48:35","modified_gmt":"2016-06-06T11:48:35","slug":"quan-luciana-duranti-baixa-del-nuvol","status":"publish","type":"post","link":"https:\/\/arxiversvalencians.org\/es\/quan-luciana-duranti-baixa-del-nuvol\/","title":{"rendered":"CUANDO LUCIANA DURANTI BAJA DE LA NUBE"},"content":{"rendered":"Afectada todav\u00eda por el Jet-lag que sufre tras su largo viaje desde Vancouver (Canad\u00e1) hasta Valencia, donde iba a inaugurar las VII Jornadas de la Asociaci\u00f3n de Archiveros Valencianos, Luciana Duranti no duda en animarse para dar su primer paseo por la ciudad. Pocas horas despu\u00e9s de aterrizar en el aeropuerto de Manises, Duranti no se muestra cansada, pero s\u00ed le cuesta un poco ubicarse tras su periplo profesional por Rusia y Noruega. Despu\u00e9s de su estancia en Valencia la esperan en Marsella, Par\u00eds, Barcelona, Bruselas, Pretoria\u2026 Hasta el 3 de diciembre, cuando ha vuelto a casa y a su trabajo en la British Columbia University.\r\n\r\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-687\" src=\"http:\/\/arxiversvalencians.org\/wordpress\/wp-content\/uploads\/2016\/06\/duranti-mercat-central-_menuda-300x225.jpg\" alt=\"Duranti Mercat Central _menuda\" width=\"300\" height=\"225\" srcset=\"https:\/\/arxiversvalencians.org\/wp-content\/uploads\/2016\/06\/duranti-mercat-central-_menuda-300x225.jpg 300w, https:\/\/arxiversvalencians.org\/wp-content\/uploads\/2016\/06\/duranti-mercat-central-_menuda-400x300.jpg 400w, https:\/\/arxiversvalencians.org\/wp-content\/uploads\/2016\/06\/duranti-mercat-central-_menuda.jpg 425w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\r\n\r\nAl visitar la Lonja de Valencia, poco a poco va situ\u00e1ndose, reencontr\u00e1ndose: deja de pensar y hablar en ingl\u00e9s para recuperar su italiano materno (naci\u00f3 en Roma -1950-) y empieza a identificarse con el g\u00f3tico y con la est\u00e9tica medieval que Valencia comparte con otros lugares de Italia, pa\u00eds que abandon\u00f3 a los 26 a\u00f1os para trasladarse a Canad\u00e1. Del templo medieval de las finanzas valencianas pasamos al Mercado Central, el templo modernista de las verduras y las frutas. Duranti admira los tenderetes llenos de colores: le entra hambre. \u201cUva, ma\u00f1ana comprar\u00e9 uva, porque la que llega a Vancuver viene de California y no sabe a nada\u201d.\r\n\r\nEsta archivera, considerada como una de las m\u00e1ximas autoridades mundiales en la investigaci\u00f3n de soluciones para la gesti\u00f3n y conservaci\u00f3n de documentos digitales y directora del programa internacional InterPARES, tiene un car\u00e1cter muy abierto, es amable, divertida, encantadora. As\u00ed es Duranti cuando baja de la \u201cnube\u201d (cloud computing), el repositorio virtual de documentos que centra sus investigaciones. El paseo por Valencia se hace muy agradable, pero tenemos que volver a la nube, y sobre esto charlamos mientras comemos una sencilla ensalada en el barrio de Carmen.\r\n\r\n<strong>\u00bfA qu\u00e9 conclusiones ha llegado tras 20 a\u00f1os de investigaci\u00f3n sobre la conservaci\u00f3n de los documentos digitales?<\/strong>\r\n\r\nCuando en Vancouver empezamos a tratar el problema de la conservaci\u00f3n de los documentos electr\u00f3nicos, entendimos que la \u00fanica forma de resolverlo era establecer una teor\u00eda que nos ayudara a encontrar soluciones pr\u00e1cticas. La tecnolog\u00eda cambia tan r\u00e1pidamente que hace falta una teor\u00eda s\u00f3lida para resolver los problemas que se generan. En nuestro trabajo en el Departamento de Defensa de los Estados Unidos planteamos la necesidad de crear el primer est\u00e1ndar de iure [v\u00e1lido legalmente, aceptado jur\u00eddicamente], que fue el DOD 5015.2, adoptado por el Gobierno Federal de los Estados Unidos en 1997. En el mundo occidental hab\u00eda otros sistemas de gesti\u00f3n de facto, pero nuestro modelo fue finalmente aceptado realmente como \u201cel est\u00e1ndar\u201d, el estandar de facto, incorporado al Moreq2.\r\n\r\nLa principal conclusi\u00f3n es que los principios que inspiraron este primer est\u00e1ndar son todav\u00eda v\u00e1lidos. Es decir, la teor\u00eda todav\u00eda es v\u00e1lida. Naturalmente, lo que cambia es la manera en que la teor\u00eda se implementa en situaciones que son completamente diferentes, con tecnolog\u00eda y tipos de documentos totalmente distintos. No se puede hablar de una soluci\u00f3n que valga para todo. Esto lo hemos descubierto en muchos estudios de campo, en los que hemos visto que organizaciones de tipos y contexto similar han obtenido resultados satisfactorios haciendo cosas completamente diferentes. La cultura de cada organizaci\u00f3n o entidad tiene un valor enorme, y por eso es muy importante estudiar primero como es cada organizaci\u00f3n, qui\u00e9n tiene que hacer uso de la tecnolog\u00eda, qu\u00e9 tipo de preparaci\u00f3n necesita, cu\u00e1les son las prioridades\u2026 Esto es el primero que se tiene que hacer antes de introducir cualquier tecnolog\u00eda. No se puede introducir un sistema de trabajo que la gente no sepa o no quiera usar, porque todo ser\u00e1n problemas.\r\n\r\nOtra conclusi\u00f3n es que los archiveros y acad\u00e9micos no pueden iniciar una investigaci\u00f3n sin principios te\u00f3ricos firmes. Y la tecnolog\u00eda cambia con tanta velocidad que la investigaci\u00f3n tiene que estar incorporada en las actividades cotidianas de la conservaci\u00f3n de documentos. Los archivos no pueden esperar a que otros resuelvan sus problemas. Son los mismos archivos los que tienen que colaborar en la mejora de la tecnolog\u00eda, en encontrar soluciones a los problemas propios. Y es muy importante, adem\u00e1s, asumir que las soluciones son siempre din\u00e1micas. La teor\u00eda es v\u00e1lida, pero el modo en que esta teor\u00eda se implementa cambia continuamente. Todas las soluciones son espec\u00edficas, es decir, est\u00e1n adaptadas a las condiciones particulares de las organizaciones donde van a ser aplicadas.\r\n\r\nEn resumen, las soluciones no son tecnol\u00f3gicas, son procedimentales, pol\u00edticas y culturales.\r\n\r\n<strong>\u00bfEs la nube segura?<\/strong>\r\n\r\n\u00a1Claro que no! Nuestra pr\u00f3xima investigaci\u00f3n se centra en los documentos en internet. Puede haber proveedores generales que no son institucionales, como por ejemplo Amazon, Google o Microsoft, pero puede haber proveedores que trabajen para ti. Es\u00a0 una cuesti\u00f3n de control del sistema, sostenibilidad, continuidad y fiabilidad. Cuando t\u00fa coges un avi\u00f3n no vas a entrevistarte con el comandante de la nave, porque te f\u00edas de \u00e9l. Con los proveedores de la nube tiene que pasar lo mismo: no necesitamos entrevistarnos cada vez, nos tenemos que fiar. Pero en este momento, todav\u00eda, los datos sensibles, los datos que tienes que conservar permanentemente no los metes en internet. No se filtrar\u00e1 aquello que no quieres que se filtre.\r\n\r\n<strong>\u00bfQu\u00e9 repercusi\u00f3n tienen sus investigaciones en la vida cotidiana de la gente? <\/strong>\r\nEl impacto es directo e indirecto. El directo se refleja en los documentos que ofrecemos con instrucciones, por ejemplo, para aquellos que no quieran perder sus fotograf\u00edas familiares. Son una serie de recomendaciones pr\u00e1cticas que sirven tanto para archiveros como para dentistas, periodistas\u2026 aquellos que tienen que conservar sus datos. Y el indirecto es que nuestras recomendaciones se convierten en est\u00e1ndares v\u00e1lidos para todas las organizaciones, y mejora el trabajo de todos los que las integran. No nos dimos cuenta del enorme impacto de nuestro trabajo hasta agosto pasado, cuando nuestro servidor fue atacado por hackers. Lo cerramos durante 20 d\u00edas para buscar todas las medidas de seguridad para que esto no volviera a pasar. Durante estos 20 d\u00edas, nos llegaron centenares de mensajes procedentes de todo el mundo: \u201c\u00bfQu\u00e9 pasa?\u201d, \u201cD\u00f3nde est\u00e1n los documentos?\u201d, \u201cNuestra organizaci\u00f3n no funciona sin vosotros!\u201d, nos dec\u00edan. Porque nuestros productos tienen muchos usos, se emplean en facultades no s\u00f3lo de archiv\u00edstica sino tambi\u00e9n de ciencias de la computaci\u00f3n, o para dise\u00f1ar m\u00f3dulos de formaci\u00f3n para cursos, asociaciones, archivos\u2026\r\n\r\n<strong>\u00bfCu\u00e1l ser\u00e1 el futuro de los archivos m\u00e1s peque\u00f1os y modestos que no pueden hacer frente al avance tecnol\u00f3gico?<\/strong>\r\n\r\nS\u00f3lo hace falta un poco dinero y un poco de experiencia con la tecnolog\u00eda. Todas las personas o archivos pueden hacer descargas y hacer uso de nuestro sistema InterPARES. Adem\u00e1s, est\u00e1 disponible en todas las lenguas. Podemos colaborar con todos. Se pueden digitalizar los materiales y meterlos en la nube. El problema de la nube es que es f\u00e1cil subir las cosas, pero imposible quitarlas. La nube es peligrosa excepto si se tiene una nube propia. Por ejemplo, los archivos valencianos peque\u00f1os se pueden poner de acuerdo con un proveedor para crear una nube adecuada, pagar a esta persona o empresa para que se dedique a ello, que controle el servidor, etc.\r\n\r\n<strong>\u00bfY que pasar\u00e1 en pa\u00edses como Italia o Espa\u00f1a, en continuo proceso de recortes en recursos?<\/strong>\r\n\u00a1No se puede recortar en estos recursos! Se pueden reducir otros servicios, pero no la inversi\u00f3n en la conservaci\u00f3n de documentos, porque si no se perder\u00e1n, se perder\u00e1n los datos, la transparencia, el funcionamiento del sistema. \u00a1Es totalmente imposible!\r\n\r\n<em><strong>Entrevista realizada per Esperan\u00e7a Costa<\/strong><\/em>","protected":false},"excerpt":{"rendered":"Afectada todav\u00eda por el Jet-lag que sufre tras su largo viaje desde Vancouver (Canad\u00e1) hasta Valencia, donde iba a inaugurar las VII Jornadas de la Asociaci\u00f3n de Archiveros Valencianos, Luciana Duranti no duda en animarse para dar su primer paseo por la ciudad. Pocas horas despu\u00e9s de aterrizar en el aeropuerto de Manises, Duranti no [&hellip;]","protected":false},"author":1,"featured_media":686,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[3],"tags":[],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CUANDO LUCIANA DURANTI BAJA DE LA NUBE - arxiversvalencians.org<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arxiversvalencians.org\/es\/quan-luciana-duranti-baixa-del-nuvol\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CUANDO LUCIANA DURANTI BAJA DE LA NUBE - arxiversvalencians.org\" \/>\n<meta property=\"og:description\" content=\"Afectada todav\u00eda por el Jet-lag que sufre tras su largo viaje desde Vancouver (Canad\u00e1) hasta Valencia, donde iba a inaugurar las VII Jornadas de la Asociaci\u00f3n de Archiveros Valencianos, Luciana Duranti no duda en animarse para dar su primer paseo por la ciudad. Pocas horas despu\u00e9s de aterrizar en el aeropuerto de Manises, Duranti no [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arxiversvalencians.org\/es\/quan-luciana-duranti-baixa-del-nuvol\/\" \/>\n<meta property=\"og:site_name\" content=\"arxiversvalencians.org\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-06T11:45:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-06-06T11:48:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arxiversvalencians.org\/wp-content\/uploads\/2016\/06\/duranti-llotja-_menuda.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"425\" \/>\n\t<meta property=\"og:image:height\" content=\"319\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/arxiversvalencians.org\/es\/quan-luciana-duranti-baixa-del-nuvol\/\",\"url\":\"https:\/\/arxiversvalencians.org\/es\/quan-luciana-duranti-baixa-del-nuvol\/\",\"name\":\"CUANDO LUCIANA DURANTI BAJA DE LA NUBE - arxiversvalencians.org\",\"isPartOf\":{\"@id\":\"https:\/\/arxiversvalencians.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/arxiversvalencians.org\/es\/quan-luciana-duranti-baixa-del-nuvol\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/arxiversvalencians.org\/es\/quan-luciana-duranti-baixa-del-nuvol\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/arxiversvalencians.org\/wp-content\/uploads\/2016\/06\/duranti-llotja-_menuda.jpg\",\"datePublished\":\"2016-06-06T11:45:30+00:00\",\"dateModified\":\"2016-06-06T11:48:35+00:00\",\"author\":{\"@id\":\"https:\/\/arxiversvalencians.org\/#\/schema\/person\/859ea9700392ee43cc340a8efe2c3781\"},\"breadcrumb\":{\"@id\":\"https:\/\/arxiversvalencians.org\/es\/quan-luciana-duranti-baixa-del-nuvol\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/arxiversvalencians.org\/es\/quan-luciana-duranti-baixa-del-nuvol\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/arxiversvalencians.org\/es\/quan-luciana-duranti-baixa-del-nuvol\/#primaryimage\",\"url\":\"https:\/\/arxiversvalencians.org\/wp-content\/uploads\/2016\/06\/duranti-llotja-_menuda.jpg\",\"contentUrl\":\"https:\/\/arxiversvalencians.org\/wp-content\/uploads\/2016\/06\/duranti-llotja-_menuda.jpg\",\"width\":425,\"height\":319},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/arxiversvalencians.org\/es\/quan-luciana-duranti-baixa-del-nuvol\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/arxiversvalencians.org\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CUANDO LUCIANA DURANTI BAJA DE LA NUBE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/arxiversvalencians.org\/#website\",\"url\":\"https:\/\/arxiversvalencians.org\/\",\"name\":\"arxiversvalencians.org\",\"description\":\"arxiversvalencians.org\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/arxiversvalencians.org\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/arxiversvalencians.org\/#\/schema\/person\/859ea9700392ee43cc340a8efe2c3781\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/arxiversvalencians.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1821ad5b9bd3d2e87653d1627e037d44?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1821ad5b9bd3d2e87653d1627e037d44?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/arxiversvalencians.org\/es\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CUANDO LUCIANA DURANTI BAJA DE LA NUBE - arxiversvalencians.org","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arxiversvalencians.org\/es\/quan-luciana-duranti-baixa-del-nuvol\/","og_locale":"es_ES","og_type":"article","og_title":"CUANDO LUCIANA DURANTI BAJA DE LA NUBE - arxiversvalencians.org","og_description":"Afectada todav\u00eda por el Jet-lag que sufre tras su largo viaje desde Vancouver (Canad\u00e1) hasta Valencia, donde iba a inaugurar las VII Jornadas de la Asociaci\u00f3n de Archiveros Valencianos, Luciana Duranti no duda en animarse para dar su primer paseo por la ciudad. Pocas horas despu\u00e9s de aterrizar en el aeropuerto de Manises, Duranti no [&hellip;]","og_url":"https:\/\/arxiversvalencians.org\/es\/quan-luciana-duranti-baixa-del-nuvol\/","og_site_name":"arxiversvalencians.org","article_published_time":"2016-06-06T11:45:30+00:00","article_modified_time":"2016-06-06T11:48:35+00:00","og_image":[{"width":425,"height":319,"url":"https:\/\/arxiversvalencians.org\/wp-content\/uploads\/2016\/06\/duranti-llotja-_menuda.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/arxiversvalencians.org\/es\/quan-luciana-duranti-baixa-del-nuvol\/","url":"https:\/\/arxiversvalencians.org\/es\/quan-luciana-duranti-baixa-del-nuvol\/","name":"CUANDO LUCIANA DURANTI BAJA DE LA NUBE - arxiversvalencians.org","isPartOf":{"@id":"https:\/\/arxiversvalencians.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/arxiversvalencians.org\/es\/quan-luciana-duranti-baixa-del-nuvol\/#primaryimage"},"image":{"@id":"https:\/\/arxiversvalencians.org\/es\/quan-luciana-duranti-baixa-del-nuvol\/#primaryimage"},"thumbnailUrl":"https:\/\/arxiversvalencians.org\/wp-content\/uploads\/2016\/06\/duranti-llotja-_menuda.jpg","datePublished":"2016-06-06T11:45:30+00:00","dateModified":"2016-06-06T11:48:35+00:00","author":{"@id":"https:\/\/arxiversvalencians.org\/#\/schema\/person\/859ea9700392ee43cc340a8efe2c3781"},"breadcrumb":{"@id":"https:\/\/arxiversvalencians.org\/es\/quan-luciana-duranti-baixa-del-nuvol\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arxiversvalencians.org\/es\/quan-luciana-duranti-baixa-del-nuvol\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/arxiversvalencians.org\/es\/quan-luciana-duranti-baixa-del-nuvol\/#primaryimage","url":"https:\/\/arxiversvalencians.org\/wp-content\/uploads\/2016\/06\/duranti-llotja-_menuda.jpg","contentUrl":"https:\/\/arxiversvalencians.org\/wp-content\/uploads\/2016\/06\/duranti-llotja-_menuda.jpg","width":425,"height":319},{"@type":"BreadcrumbList","@id":"https:\/\/arxiversvalencians.org\/es\/quan-luciana-duranti-baixa-del-nuvol\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/arxiversvalencians.org\/es\/"},{"@type":"ListItem","position":2,"name":"CUANDO LUCIANA DURANTI BAJA DE LA NUBE"}]},{"@type":"WebSite","@id":"https:\/\/arxiversvalencians.org\/#website","url":"https:\/\/arxiversvalencians.org\/","name":"arxiversvalencians.org","description":"arxiversvalencians.org","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arxiversvalencians.org\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/arxiversvalencians.org\/#\/schema\/person\/859ea9700392ee43cc340a8efe2c3781","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/arxiversvalencians.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1821ad5b9bd3d2e87653d1627e037d44?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1821ad5b9bd3d2e87653d1627e037d44?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/arxiversvalencians.org\/es\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/arxiversvalencians.org\/wp-content\/uploads\/2016\/06\/duranti-llotja-_menuda.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7fqQj-b8","_links":{"self":[{"href":"https:\/\/arxiversvalencians.org\/es\/wp-json\/wp\/v2\/posts\/690"}],"collection":[{"href":"https:\/\/arxiversvalencians.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arxiversvalencians.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arxiversvalencians.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/arxiversvalencians.org\/es\/wp-json\/wp\/v2\/comments?post=690"}],"version-history":[{"count":2,"href":"https:\/\/arxiversvalencians.org\/es\/wp-json\/wp\/v2\/posts\/690\/revisions"}],"predecessor-version":[{"id":692,"href":"https:\/\/arxiversvalencians.org\/es\/wp-json\/wp\/v2\/posts\/690\/revisions\/692"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arxiversvalencians.org\/es\/wp-json\/wp\/v2\/media\/686"}],"wp:attachment":[{"href":"https:\/\/arxiversvalencians.org\/es\/wp-json\/wp\/v2\/media?parent=690"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arxiversvalencians.org\/es\/wp-json\/wp\/v2\/categories?post=690"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arxiversvalencians.org\/es\/wp-json\/wp\/v2\/tags?post=690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}