{"id":13635,"date":"2024-02-19T18:52:02","date_gmt":"2024-02-19T17:52:02","guid":{"rendered":"https:\/\/arxivers.estudigrafema.com\/?p=13635"},"modified":"2024-07-17T10:43:32","modified_gmt":"2024-07-17T09:43:32","slug":"formacion-2024-curso-3-crear-una-exposicion-en-linea","status":"publish","type":"post","link":"https:\/\/arxiversvalencians.org\/es\/formacion-2024-curso-3-crear-una-exposicion-en-linea\/","title":{"rendered":"Formaci\u00f3n 2024. Curso (3): Crear una exposici\u00f3n en l\u00ednea"},"content":{"rendered":"<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-12951 size-large\" src=\"https:\/\/arxiversvalencians.org\/wp-content\/uploads\/2024\/02\/cartel-expo-online-cas-1-724x1024.png\" alt=\"\" width=\"724\" height=\"1024\" \/>\r\n\r\n<strong>La nueva Plataforma ArxiuFormaci\u00f3 es una herramienta de desarrollo para los cursos de aprendizaje virtual. <div class=\"clear\"><\/div><div class=\"gdlr-space\" style=\"margin-top: 20px;\"><\/div><\/strong>\r\n\r\nEnlace: <a href=\"https:\/\/www.arxiuformacio.org\/inici\/\">https:\/\/www.arxiuformacio.org\/inici\/<\/a><strong> <div class=\"clear\"><\/div><div class=\"gdlr-space\" style=\"margin-top: 20px;\"><\/div><\/strong>\r\n\r\n<strong>3er Curso: Crear una exposici\u00f3n en l\u00ednea (2) <div class=\"clear\"><\/div><div class=\"gdlr-space\" style=\"margin-top: 20px;\"><\/div><\/strong>\r\n<ul>\r\n \t<li>Fecha: <strong>Aplazado\u00a0por motivos de organizaci\u00f3n hasta 2025, informaremos en breve de la nueva fecha.<\/strong><\/li>\r\n \t<li>Duraci\u00f3n: 20 horas.<\/li>\r\n \t<li>Plazas limitadas.<\/li>\r\n \t<li>Gratuito, solo para socios\/as.<\/li>\r\n \t<li>Informaci\u00f3n: secretaria@arxiversvalencians.org<\/li>\r\n<\/ul>\r\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-12953 size-large\" src=\"https:\/\/arxiversvalencians.org\/wp-content\/uploads\/2024\/02\/cartel-expo-online-cas-2-724x1024.png\" alt=\"\" width=\"724\" height=\"1024\" \/>\r\n\r\n<strong>\u00bfC\u00f3mo puedes hacer el curso?<\/strong> El proceso es el siguiente y lo puedes encontrar en la \u00a0<a href=\"https:\/\/www.arxiuformacio.org\/inici\/\">web:<\/a><strong> <div class=\"clear\"><\/div><div class=\"gdlr-space\" style=\"margin-top: 20px;\"><\/div><\/strong>\r\n<ol>\r\n \t<li>As\u00f3ciate para poder tener acceso a los cursos de la Plataforma.<\/li>\r\n \t<li>Reg\u00edstrate, es necesario para poder acceder al contenido de los cursos.<\/li>\r\n \t<li>Espera confirmaci\u00f3n de acceso a la Plataforma.<\/li>\r\n \t<li>Accede al escritorio de la plataforma del alumnado.<\/li>\r\n<\/ol>","protected":false},"excerpt":{"rendered":"La nueva Plataforma ArxiuFormaci\u00f3 es una herramienta de desarrollo para los cursos de aprendizaje virtual. Enlace: https:\/\/www.arxiuformacio.org\/inici\/ 3er Curso: Crear una exposici\u00f3n en l\u00ednea (2) Fecha: Aplazado\u00a0por motivos de organizaci\u00f3n hasta 2025, informaremos en breve de la nueva fecha. Duraci\u00f3n: 20 horas. Plazas limitadas. Gratuito, solo para socios\/as. Informaci\u00f3n: secretaria@arxiversvalencians.org \u00bfC\u00f3mo puedes hacer el curso? [&hellip;]","protected":false},"author":1,"featured_media":13730,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[9,3],"tags":[78,103],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Formaci\u00f3n 2024. Curso (3): Crear una exposici\u00f3n en l\u00ednea - arxiversvalencians.org<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arxiversvalencians.org\/es\/formacion-2024-curso-3-crear-una-exposicion-en-linea\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Formaci\u00f3n 2024. Curso (3): Crear una exposici\u00f3n en l\u00ednea - arxiversvalencians.org\" \/>\n<meta property=\"og:description\" content=\"La nueva Plataforma ArxiuFormaci\u00f3 es una herramienta de desarrollo para los cursos de aprendizaje virtual. Enlace: https:\/\/www.arxiuformacio.org\/inici\/ 3er Curso: Crear una exposici\u00f3n en l\u00ednea (2) Fecha: Aplazado\u00a0por motivos de organizaci\u00f3n hasta 2025, informaremos en breve de la nueva fecha. Duraci\u00f3n: 20 horas. Plazas limitadas. Gratuito, solo para socios\/as. Informaci\u00f3n: secretaria@arxiversvalencians.org \u00bfC\u00f3mo puedes hacer el curso? [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arxiversvalencians.org\/es\/formacion-2024-curso-3-crear-una-exposicion-en-linea\/\" \/>\n<meta property=\"og:site_name\" content=\"arxiversvalencians.org\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-19T17:52:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-17T09:43:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arxiversvalencians.org\/wp-content\/uploads\/2024\/02\/cartell-expo-online-val-11.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1754\" \/>\n\t<meta property=\"og:image:height\" content=\"2480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/arxiversvalencians.org\/es\/formacion-2024-curso-3-crear-una-exposicion-en-linea\/\",\"url\":\"https:\/\/arxiversvalencians.org\/es\/formacion-2024-curso-3-crear-una-exposicion-en-linea\/\",\"name\":\"Formaci\u00f3n 2024. Curso (3): Crear una exposici\u00f3n en l\u00ednea - arxiversvalencians.org\",\"isPartOf\":{\"@id\":\"https:\/\/arxiversvalencians.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/arxiversvalencians.org\/es\/formacion-2024-curso-3-crear-una-exposicion-en-linea\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/arxiversvalencians.org\/es\/formacion-2024-curso-3-crear-una-exposicion-en-linea\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/arxiversvalencians.org\/wp-content\/uploads\/2024\/02\/cartell-expo-online-val-11.png\",\"datePublished\":\"2024-02-19T17:52:02+00:00\",\"dateModified\":\"2024-07-17T09:43:32+00:00\",\"author\":{\"@id\":\"https:\/\/arxiversvalencians.org\/#\/schema\/person\/859ea9700392ee43cc340a8efe2c3781\"},\"breadcrumb\":{\"@id\":\"https:\/\/arxiversvalencians.org\/es\/formacion-2024-curso-3-crear-una-exposicion-en-linea\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/arxiversvalencians.org\/es\/formacion-2024-curso-3-crear-una-exposicion-en-linea\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/arxiversvalencians.org\/es\/formacion-2024-curso-3-crear-una-exposicion-en-linea\/#primaryimage\",\"url\":\"https:\/\/arxiversvalencians.org\/wp-content\/uploads\/2024\/02\/cartell-expo-online-val-11.png\",\"contentUrl\":\"https:\/\/arxiversvalencians.org\/wp-content\/uploads\/2024\/02\/cartell-expo-online-val-11.png\",\"width\":1754,\"height\":2480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/arxiversvalencians.org\/es\/formacion-2024-curso-3-crear-una-exposicion-en-linea\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/arxiversvalencians.org\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Formaci\u00f3n 2024. Curso (3): Crear una exposici\u00f3n en l\u00ednea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/arxiversvalencians.org\/#website\",\"url\":\"https:\/\/arxiversvalencians.org\/\",\"name\":\"arxiversvalencians.org\",\"description\":\"arxiversvalencians.org\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/arxiversvalencians.org\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/arxiversvalencians.org\/#\/schema\/person\/859ea9700392ee43cc340a8efe2c3781\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/arxiversvalencians.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1821ad5b9bd3d2e87653d1627e037d44?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1821ad5b9bd3d2e87653d1627e037d44?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/arxiversvalencians.org\/es\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Formaci\u00f3n 2024. Curso (3): Crear una exposici\u00f3n en l\u00ednea - arxiversvalencians.org","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arxiversvalencians.org\/es\/formacion-2024-curso-3-crear-una-exposicion-en-linea\/","og_locale":"es_ES","og_type":"article","og_title":"Formaci\u00f3n 2024. Curso (3): Crear una exposici\u00f3n en l\u00ednea - arxiversvalencians.org","og_description":"La nueva Plataforma ArxiuFormaci\u00f3 es una herramienta de desarrollo para los cursos de aprendizaje virtual. Enlace: https:\/\/www.arxiuformacio.org\/inici\/ 3er Curso: Crear una exposici\u00f3n en l\u00ednea (2) Fecha: Aplazado\u00a0por motivos de organizaci\u00f3n hasta 2025, informaremos en breve de la nueva fecha. Duraci\u00f3n: 20 horas. Plazas limitadas. Gratuito, solo para socios\/as. Informaci\u00f3n: secretaria@arxiversvalencians.org \u00bfC\u00f3mo puedes hacer el curso? [&hellip;]","og_url":"https:\/\/arxiversvalencians.org\/es\/formacion-2024-curso-3-crear-una-exposicion-en-linea\/","og_site_name":"arxiversvalencians.org","article_published_time":"2024-02-19T17:52:02+00:00","article_modified_time":"2024-07-17T09:43:32+00:00","og_image":[{"width":1754,"height":2480,"url":"https:\/\/arxiversvalencians.org\/wp-content\/uploads\/2024\/02\/cartell-expo-online-val-11.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/arxiversvalencians.org\/es\/formacion-2024-curso-3-crear-una-exposicion-en-linea\/","url":"https:\/\/arxiversvalencians.org\/es\/formacion-2024-curso-3-crear-una-exposicion-en-linea\/","name":"Formaci\u00f3n 2024. Curso (3): Crear una exposici\u00f3n en l\u00ednea - arxiversvalencians.org","isPartOf":{"@id":"https:\/\/arxiversvalencians.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/arxiversvalencians.org\/es\/formacion-2024-curso-3-crear-una-exposicion-en-linea\/#primaryimage"},"image":{"@id":"https:\/\/arxiversvalencians.org\/es\/formacion-2024-curso-3-crear-una-exposicion-en-linea\/#primaryimage"},"thumbnailUrl":"https:\/\/arxiversvalencians.org\/wp-content\/uploads\/2024\/02\/cartell-expo-online-val-11.png","datePublished":"2024-02-19T17:52:02+00:00","dateModified":"2024-07-17T09:43:32+00:00","author":{"@id":"https:\/\/arxiversvalencians.org\/#\/schema\/person\/859ea9700392ee43cc340a8efe2c3781"},"breadcrumb":{"@id":"https:\/\/arxiversvalencians.org\/es\/formacion-2024-curso-3-crear-una-exposicion-en-linea\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arxiversvalencians.org\/es\/formacion-2024-curso-3-crear-una-exposicion-en-linea\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/arxiversvalencians.org\/es\/formacion-2024-curso-3-crear-una-exposicion-en-linea\/#primaryimage","url":"https:\/\/arxiversvalencians.org\/wp-content\/uploads\/2024\/02\/cartell-expo-online-val-11.png","contentUrl":"https:\/\/arxiversvalencians.org\/wp-content\/uploads\/2024\/02\/cartell-expo-online-val-11.png","width":1754,"height":2480},{"@type":"BreadcrumbList","@id":"https:\/\/arxiversvalencians.org\/es\/formacion-2024-curso-3-crear-una-exposicion-en-linea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/arxiversvalencians.org\/es\/"},{"@type":"ListItem","position":2,"name":"Formaci\u00f3n 2024. Curso (3): Crear una exposici\u00f3n en l\u00ednea"}]},{"@type":"WebSite","@id":"https:\/\/arxiversvalencians.org\/#website","url":"https:\/\/arxiversvalencians.org\/","name":"arxiversvalencians.org","description":"arxiversvalencians.org","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arxiversvalencians.org\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/arxiversvalencians.org\/#\/schema\/person\/859ea9700392ee43cc340a8efe2c3781","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/arxiversvalencians.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1821ad5b9bd3d2e87653d1627e037d44?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1821ad5b9bd3d2e87653d1627e037d44?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/arxiversvalencians.org\/es\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/arxiversvalencians.org\/wp-content\/uploads\/2024\/02\/cartell-expo-online-val-11.png","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7fqQj-3xV","_links":{"self":[{"href":"https:\/\/arxiversvalencians.org\/es\/wp-json\/wp\/v2\/posts\/13635"}],"collection":[{"href":"https:\/\/arxiversvalencians.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arxiversvalencians.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arxiversvalencians.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/arxiversvalencians.org\/es\/wp-json\/wp\/v2\/comments?post=13635"}],"version-history":[{"count":5,"href":"https:\/\/arxiversvalencians.org\/es\/wp-json\/wp\/v2\/posts\/13635\/revisions"}],"predecessor-version":[{"id":13930,"href":"https:\/\/arxiversvalencians.org\/es\/wp-json\/wp\/v2\/posts\/13635\/revisions\/13930"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arxiversvalencians.org\/es\/wp-json\/wp\/v2\/media\/13730"}],"wp:attachment":[{"href":"https:\/\/arxiversvalencians.org\/es\/wp-json\/wp\/v2\/media?parent=13635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arxiversvalencians.org\/es\/wp-json\/wp\/v2\/categories?post=13635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arxiversvalencians.org\/es\/wp-json\/wp\/v2\/tags?post=13635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}